{"id":23229,"date":"2024-02-09T10:59:36","date_gmt":"2024-02-09T09:59:36","guid":{"rendered":"https:\/\/www.ogbl.lu\/?post_type=mediatheque&#038;p=23229"},"modified":"2024-02-14T13:55:44","modified_gmt":"2024-02-14T12:55:44","slug":"fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner","status":"publish","type":"mediatheque","link":"https:\/\/www.ogbl.lu\/en\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/","title":{"rendered":"Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\"> <\/p><p><span class=\"yt-core-attributed-string yt-core-attributed-string--white-space-pre-wrap\" role=\"text\"><span class=\"yt-core-attributed-string--link-inherit-color\">Usprooch vum Jean-Claude Reding um Dag vun de Pension\u00e9ierten am OGBL &#8211; 9. Februar 2024<\/span><\/span><\/p>","protected":false},"featured_media":23304,"template":"","type_mediatheque":[60],"syndicat":[118],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title><\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"[:fr]Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner [:] - OGBL\" \/>\r\n<meta property=\"og:description\" content=\"Usprooch vum Jean-Claude Reding um Dag vun de Pension\u00e9ierten am OGBL &#8211; 9. Februar 2024\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/\" \/>\r\n<meta property=\"og:site_name\" content=\"OGBL\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-02-14T12:55:44+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/\",\"url\":\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/\",\"name\":\"[:fr]Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner [:] - OGBL\",\"isPartOf\":{\"@id\":\"https:\/\/www.ogbl.lu\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg\",\"datePublished\":\"2024-02-09T09:59:36+00:00\",\"dateModified\":\"2024-02-14T12:55:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#primaryimage\",\"url\":\"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg\",\"contentUrl\":\"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.ogbl.lu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ogbl.lu\/de\/#website\",\"url\":\"https:\/\/www.ogbl.lu\/de\/\",\"name\":\"OGBL\",\"description\":\"THE TRADE UNION\",\"publisher\":{\"@id\":\"https:\/\/www.ogbl.lu\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ogbl.lu\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.ogbl.lu\/de\/#organization\",\"name\":\"OGBL\",\"url\":\"https:\/\/www.ogbl.lu\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.ogbl.lu\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/07\/LOGO_Red_FR-svg.png\",\"contentUrl\":\"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/07\/LOGO_Red_FR-svg.png\",\"width\":369,\"height\":171,\"caption\":\"OGBL\"},\"image\":{\"@id\":\"https:\/\/www.ogbl.lu\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:fr]Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner [:] - OGBL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/","og_locale":"en_US","og_type":"article","og_title":"[:fr]Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner [:] - OGBL","og_description":"Usprooch vum Jean-Claude Reding um Dag vun de Pension\u00e9ierten am OGBL &#8211; 9. Februar 2024","og_url":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/","og_site_name":"OGBL","article_modified_time":"2024-02-14T12:55:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/","url":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/","name":"[:fr]Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner [:] - OGBL","isPartOf":{"@id":"https:\/\/www.ogbl.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#primaryimage"},"image":{"@id":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg","datePublished":"2024-02-09T09:59:36+00:00","dateModified":"2024-02-14T12:55:44+00:00","breadcrumb":{"@id":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#primaryimage","url":"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg","contentUrl":"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/02\/video_09022024_LU_vignette.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.ogbl.lu\/mediatheque\/media\/fangeren-ewech-vun-eise-pensiounen-a-vun-de-pensiounen-vun-eise-kanner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ogbl.lu\/"},{"@type":"ListItem","position":2,"name":"Fangeren ewech vun eise Pensiounen a vun de Pensiounen vun eise Kanner"}]},{"@type":"WebSite","@id":"https:\/\/www.ogbl.lu\/de\/#website","url":"https:\/\/www.ogbl.lu\/de\/","name":"OGBL","description":"THE TRADE UNION","publisher":{"@id":"https:\/\/www.ogbl.lu\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ogbl.lu\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.ogbl.lu\/de\/#organization","name":"OGBL","url":"https:\/\/www.ogbl.lu\/de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.ogbl.lu\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/07\/LOGO_Red_FR-svg.png","contentUrl":"https:\/\/www.ogbl.lu\/wp-content\/uploads\/2024\/07\/LOGO_Red_FR-svg.png","width":369,"height":171,"caption":"OGBL"},"image":{"@id":"https:\/\/www.ogbl.lu\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.ogbl.lu\/en\/wp-json\/wp\/v2\/mediatheque\/23229"}],"collection":[{"href":"https:\/\/www.ogbl.lu\/en\/wp-json\/wp\/v2\/mediatheque"}],"about":[{"href":"https:\/\/www.ogbl.lu\/en\/wp-json\/wp\/v2\/types\/mediatheque"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ogbl.lu\/en\/wp-json\/wp\/v2\/media\/23304"}],"wp:attachment":[{"href":"https:\/\/www.ogbl.lu\/en\/wp-json\/wp\/v2\/media?parent=23229"}],"wp:term":[{"taxonomy":"type_mediatheque","embeddable":true,"href":"https:\/\/www.ogbl.lu\/en\/wp-json\/wp\/v2\/type_mediatheque?post=23229"},{"taxonomy":"syndicat","embeddable":true,"href":"https:\/\/www.ogbl.lu\/en\/wp-json\/wp\/v2\/syndicat?post=23229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}